{"id":1529,"date":"2025-09-09T17:30:18","date_gmt":"2025-09-09T20:30:18","guid":{"rendered":"https:\/\/plazacolonia.com.uy\/plaza\/?p=1529"},"modified":"2025-09-09T20:45:31","modified_gmt":"2025-09-09T23:45:31","slug":"emotivo-reconocimiento-a-jugadores-de-la-seleccion-uruguaya-de-futbol-para-amputados","status":"publish","type":"post","link":"https:\/\/plazacolonia.com.uy\/plaza\/2025\/09\/09\/emotivo-reconocimiento-a-jugadores-de-la-seleccion-uruguaya-de-futbol-para-amputados\/","title":{"rendered":"Emotivo reconocimiento a los jugadores de la Selecci\u00f3n Uruguaya de F\u00fatbol para Amputados"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">El pasado s\u00e1bado 6 de setiembre se celebr\u00f3 la cuarta edici\u00f3n de Plaza de Sabores, un evento gastron\u00f3mico solidario que volvi\u00f3 a consolidarse como una de las fiestas m\u00e1s importantes de la regi\u00f3n. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">Con un gran marco de p\u00fablico y el entusiasmo de decenas de emprendedores y m\u00faltiples propuestas culinarias, la jornada se desarroll\u00f3 a beneficio de Plaza Inclusivo, el proyecto del Club Plaza de Deportes Colonia que trabaja en la integraci\u00f3n a trav\u00e9s del deporte. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">En este marco, se realiz\u00f3 un reconocimiento especial a Cristian But\u00edn, Franco Medero y Luciano Varela, tres deportistas colonienses que integraron la selecci\u00f3n uruguaya de F\u00fatbol para Amputados, que se consagrara vicecampeona Sudamericana en Brasil y clasificara al Mundial de Costa Rica 2026. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">El homenaje fue recibido con una ovaci\u00f3n por parte del p\u00fablico, en el que se destac\u00f3 el esfuerzo, la dedicaci\u00f3n y el ejemplo de superaci\u00f3n que representan para toda la comunidad. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">Adem\u00e1s de los homenajes, Plaza de Sabores volvi\u00f3 a reunir lo mejor de la gastronom\u00eda local y regional, en una propuesta que combin\u00f3 sabores, solidaridad y encuentro social. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">\u201cCada a\u00f1o Plaza de Sabores crece un poco m\u00e1s y confirma que es una verdadera fiesta de la comunidad, que no solo apoya a Plaza Inclusivo, sino que tambi\u00e9n proyecta a Colonia como un polo gastron\u00f3mico y cultural\u201d, se\u00f1alaron desde la organizaci\u00f3n. <\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\" style=\"font-size:20px;font-style:normal;font-weight:400\">El evento, que se ha transformado en un cl\u00e1sico del calendario coloniense, reafirm\u00f3 su doble valor: por un lado, como instancia de integraci\u00f3n social y apoyo a proyectos deportivos inclusivos; y por otro, como un espacio de disfrute y celebraci\u00f3n para toda la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado 6 de setiembre se celebr\u00f3 la cuarta edici\u00f3n de Plaza de Sabores, un evento gastron\u00f3mico solidario que volvi\u00f3 a consolidarse como una de las fiestas m\u00e1s importantes de la regi\u00f3n. Con un gran marco de p\u00fablico y el entusiasmo de decenas de emprendedores y m\u00faltiples propuestas culinarias, la jornada se desarroll\u00f3 a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,3],"tags":[],"class_list":["post-1529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusion","category-novedades"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/plazacolonia.com.uy\/plaza\/wp-content\/uploads\/2025\/09\/amputados.jpg","_links":{"self":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/comments?post=1529"}],"version-history":[{"count":2,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/1529\/revisions"}],"predecessor-version":[{"id":1532,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/1529\/revisions\/1532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/media\/1530"}],"wp:attachment":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/media?parent=1529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/categories?post=1529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/tags?post=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}