{"id":751,"date":"2024-04-23T11:11:31","date_gmt":"2024-04-23T14:11:31","guid":{"rendered":"https:\/\/plazacolonia.com.uy\/plaza\/?p=751"},"modified":"2024-04-23T11:11:33","modified_gmt":"2024-04-23T14:11:33","slug":"vamos-por-mas-encuentros","status":"publish","type":"post","link":"https:\/\/plazacolonia.com.uy\/plaza\/2024\/04\/23\/vamos-por-mas-encuentros\/","title":{"rendered":"Vamos por m\u00e1s encuentros!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El segundo encuentro de deportes adaptados no tenia como finalidad la competicion, sino el encuentro, jugar al futbol y pasarla bien con los otros equipos. No se contabilizaban los goles, no habia un solo ganador, todos eran ganadores. Se entregaron medallas a los jugadores y al equipo tecnico. Se realizaron partidos de futbol adaptados entre un equipo integrado por chicos de la huerta y dos de plaza inclusivo, que representaron a plaza en un partido vs sportivo rodo. Al igual que partidos de futsal down.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se espera y proyectan diferentes encuentros y competiciones de deportes adaptados y futsal down durante el a\u00f1o en Montevideo, Salto y otras localidades del pais.<br>No hay fechas definidas aun, pero no van a faltar oportunidades para volvernos a encontrar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El segundo encuentro de deportes adaptados no tenia como finalidad la competicion, sino el encuentro, jugar al futbol y pasarla bien con los otros equipos. No se contabilizaban los goles, no habia un solo ganador, todos eran ganadores. Se entregaron medallas a los jugadores y al equipo tecnico. Se realizaron partidos de futbol adaptados entre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,3],"tags":[],"class_list":["post-751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inclusion","category-novedades"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/plazacolonia.com.uy\/plaza\/wp-content\/uploads\/2024\/04\/IMG_20240423_110709.jpg","_links":{"self":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":1,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/751\/revisions"}],"predecessor-version":[{"id":753,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/posts\/751\/revisions\/753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/media\/752"}],"wp:attachment":[{"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/categories?post=751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/plazacolonia.com.uy\/plaza\/wp-json\/wp\/v2\/tags?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}